{"id":5406,"date":"2026-08-17T15:15:21","date_gmt":"2026-08-17T08:15:21","guid":{"rendered":"https:\/\/rdi.rmutsv.ac.th\/rspg\/?p=5406"},"modified":"2026-08-19T11:29:55","modified_gmt":"2026-08-19T04:29:55","slug":"%e0%b8%a8%e0%b8%b9%e0%b8%99%e0%b8%a2%e0%b9%8c%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%b2%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%9e-%e0%b8%aa%e0%b8%98-%e0%b8%a1%e0%b8%ab%e0%b8%b2-3","status":"publish","type":"post","link":"https:\/\/rdi.rmutsv.ac.th\/rspg\/2026\/08\/17\/5406\/","title":{"rendered":"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e2d\u0e1e.\u0e2a\u0e18. \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e23\u0e32\u0e0a\u0e21\u0e07\u0e04\u0e25\u0e28\u0e23\u0e35\u0e27\u0e34\u0e0a\u0e31\u0e22 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e40\u0e22\u0e35\u0e22\u0e19\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e30\u0e41\u0e19\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Zoom Meeting \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 14 \u2013 17 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2569"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e42\u0e14\u0e22\u0e21\u0e35\u0e04\u0e38\u0e13\u0e21\u0e23\u0e01\u0e15 \u0e27\u0e31\u0e0a\u0e23\u0e21\u0e38\u0e2a\u0e34\u0e01 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23 \u0e2d\u0e1e.\u0e2a\u0e18. \u0e41\u0e19\u0e30\u0e19\u0e33\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e40\u0e22\u0e35\u0e22\u0e19\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e30\u0e41\u0e19\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e27\u0e19\u0e1e\u0e24\u0e01\u0e29\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e08\u0e32\u0e01\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e1e.\u0e2a\u0e18. \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e23\u0e32\u0e0a\u0e21\u0e07\u0e04\u0e25\u0e28\u0e23\u0e35\u0e27\u0e34\u0e0a\u0e31\u0e22 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e2d\u0e1e.\u0e2a\u0e18. \u0e21\u0e27\u0e25. \u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e2d\u0e1e.\u0e2a\u0e18. \u0e41\u0e21\u0e48\u0e42\u0e08\u0e49 \u0e0a\u0e38\u0e21\u0e1e\u0e23 \u0e23\u0e48\u0e27\u0e21\u0e2a\u0e23\u0e38\u0e1b\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e07\u0e32\u0e19 \u0e14\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48 1 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e14\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48 2 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 \u0e14\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48 3 \u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30 3 \u0e2a\u0e32\u0e23\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 : \u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e48\u0e07\u0e25\u0e49\u0e27\u0e19\u0e1e\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27 \u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e17\u0e49\u0e41\u0e01\u0e48\u0e21\u0e2b\u0e32\u0e0a\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e20\u0e32\u0e1e\u0e23\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e40\u0e22\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e30\u0e41\u0e19\u0e19\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e27\u0e19\u0e1e\u0e24\u0e01\u0e29\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19<br>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e0b\u0e36\u0e48\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e35\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e2d\u0e1e.\u0e2a\u0e18. \u0e21\u0e27\u0e25.\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e2d\u0e1e.\u0e2a\u0e18. \u0e41\u0e21\u0e48\u0e42\u0e08\u0e49 \u0e0a\u0e38\u0e21\u0e1e\u0e23 \u0e23\u0e23.\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c\u0e23\u0e31\u0e15\u0e19\u0e32\u0e20\u0e34\u0e21\u0e38\u0e02 \u0e23\u0e23.\u0e1a\u0e49\u0e32\u0e19\u0e04\u0e31\u0e19\u0e18\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e23.\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07 \u0e23\u0e23.\u0e44\u0e17\u0e22\u0e23\u0e31\u0e10\u0e27\u0e34\u0e17\u0e22\u0e32 97 (\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19) \u0e23\u0e23.\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e23\u0e30\u0e21\u0e48\u0e27\u0e07<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e2d\u0e1e.\u0e2a\u0e18. \u0e20\u0e32\u0e04\u0e43\u0e15\u0e49\u0e1d\u0e31\u0e48\u0e07\u0e2d\u0e31\u0e19\u0e14\u0e32\u0e21\u0e31\u0e19 (\u0e2d\u0e1e.\u0e2a\u0e18.-\u0e21\u0e17\u0e23.\u0e28\u0e23\u0e35\u0e27\u0e34\u0e0a\u0e31\u0e22)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e23\u0e32\u0e0a\u0e21\u0e07\u0e04\u0e25\u0e28\u0e23\u0e35\u0e27\u0e34\u0e0a\u0e31\u0e22<\/p>\n\n\n\n<h1 class=\"wp-block-heading\"><\/h1>\n\n\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-masonry.kb-gallery-id-5406_d646df-70{margin:-5px;}.kb-gallery-type-masonry.kb-gallery-id-5406_d646df-70 .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-5406_d646df-70 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-5406_d646df-70 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-5406_d646df-70 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-masonry kb-masonry-init kb-gallery-id-5406_d646df-70 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-2.jpg\" class=\"kb-gallery-item-link\"  ><div class=\"kb-gal-image-radius\" style=\"max-width:750px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-2-1024x576.jpg\" width=\"750\" height=\"422\" alt=\"\" data-full-image=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-2.jpg\" data-light-image=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-2.jpg\" data-id=\"5412\" class=\"wp-image-5412\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-2-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-2-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-2-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-2-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-2.jpg 1920w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-3.jpg\" class=\"kb-gallery-item-link\"  ><div class=\"kb-gal-image-radius\" style=\"max-width:750px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-3-1024x576.jpg\" width=\"750\" height=\"422\" alt=\"\" data-full-image=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-3.jpg\" data-light-image=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-3.jpg\" data-id=\"5415\" class=\"wp-image-5415\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-3-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-3-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-3-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-3-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-3.jpg 1920w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-4.jpg\" class=\"kb-gallery-item-link\"  ><div class=\"kb-gal-image-radius\" style=\"max-width:750px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-4-1024x576.jpg\" width=\"750\" height=\"422\" alt=\"\" data-full-image=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-4.jpg\" data-light-image=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-4.jpg\" data-id=\"5418\" class=\"wp-image-5418\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-4-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-4-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-4-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-4-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-4.jpg 1920w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-5.jpg\" class=\"kb-gallery-item-link\"  ><div class=\"kb-gal-image-radius\" style=\"max-width:750px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-5-1024x576.jpg\" width=\"750\" height=\"422\" alt=\"\" data-full-image=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-5.jpg\" data-light-image=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-5.jpg\" data-id=\"5421\" class=\"wp-image-5421\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-5-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-5-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-5-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-5-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-5.jpg 1920w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-6.jpg\" class=\"kb-gallery-item-link\"  ><div class=\"kb-gal-image-radius\" style=\"max-width:750px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:56%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-6-1024x576.jpg\" width=\"750\" height=\"422\" alt=\"\" data-full-image=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-6.jpg\" data-light-image=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-6.jpg\" data-id=\"5424\" class=\"wp-image-5424\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-6-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-6-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-6-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-6-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/1-6.jpg 1920w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><\/ul><\/div>\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5577\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-1-1024x576.jpg\" alt=\"\" class=\"wp-image-5577\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-1-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-1-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-1-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-1-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-1.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5586\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-2-1024x576.jpg\" alt=\"\" class=\"wp-image-5586\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-2-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-2-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-2-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-2-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-2.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5571\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-3-1024x576.jpg\" alt=\"\" class=\"wp-image-5571\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-3-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-3-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-3-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-3-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-3.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5604\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-4-1024x576.jpg\" alt=\"\" class=\"wp-image-5604\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-4-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-4-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-4-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-4-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-4.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5607\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-5-1024x576.jpg\" alt=\"\" class=\"wp-image-5607\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-5-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-5-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-5-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-5-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-5.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5598\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-6-1024x576.jpg\" alt=\"\" class=\"wp-image-5598\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-6-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-6-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-6-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-6-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-6.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5592\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-7-1024x576.jpg\" alt=\"\" class=\"wp-image-5592\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-7-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-7-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-7-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-7-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-7.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5601\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-8-1024x576.jpg\" alt=\"\" class=\"wp-image-5601\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-8-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-8-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-8-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-8-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-8.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5610\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-9-1024x576.jpg\" alt=\"\" class=\"wp-image-5610\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-9-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-9-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-9-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-9-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-9.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5595\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-10-1024x576.jpg\" alt=\"\" class=\"wp-image-5595\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-10-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-10-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-10-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-10-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-10.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5589\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-11-1024x576.jpg\" alt=\"\" class=\"wp-image-5589\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-11-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-11-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-11-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-11-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-11.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5580\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-12-1024x576.jpg\" alt=\"\" class=\"wp-image-5580\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-12-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-12-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-12-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-12-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-12.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5568\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-13-1024x576.jpg\" alt=\"\" class=\"wp-image-5568\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-13-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-13-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-13-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-13-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-13.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5574\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-14-1024x576.jpg\" alt=\"\" class=\"wp-image-5574\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-14-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-14-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-14-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-14-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-14.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5583\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-15-1024x576.jpg\" alt=\"\" class=\"wp-image-5583\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-15-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-15-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-15-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-15-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-15.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5613\" src=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-16-1024x576.jpg\" alt=\"\" class=\"wp-image-5613\" srcset=\"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-16-1024x576.jpg 1024w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-16-300x169.jpg 300w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-16-768x432.jpg 768w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-16-1536x864.jpg 1536w, https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-content\/uploads\/2026\/08\/072569-16.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e42\u0e14\u0e22\u0e21\u0e35\u0e04\u0e38\u0e13\u0e21\u0e23\u0e01\u0e15 \u0e27\u0e31\u0e0a\u0e23\u0e21\u0e38\u0e2a\u0e34\u0e01 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23 \u0e2d\u0e1e.\u0e2a\u0e18. \u0e41\u0e19\u0e30\u0e19\u0e33\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":5409,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5,11],"tags":[],"class_list":["post-5406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rspg-hilight-pr","category-rspg-school"],"acf":[],"_links":{"self":[{"href":"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-json\/wp\/v2\/posts\/5406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-json\/wp\/v2\/comments?post=5406"}],"version-history":[{"count":2,"href":"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-json\/wp\/v2\/posts\/5406\/revisions"}],"predecessor-version":[{"id":5616,"href":"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-json\/wp\/v2\/posts\/5406\/revisions\/5616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-json\/wp\/v2\/media\/5409"}],"wp:attachment":[{"href":"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-json\/wp\/v2\/media?parent=5406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-json\/wp\/v2\/categories?post=5406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rdi.rmutsv.ac.th\/rspg\/wp-json\/wp\/v2\/tags?post=5406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}